{"id":16764,"date":"2025-12-10T12:35:59","date_gmt":"2025-12-10T11:35:59","guid":{"rendered":"http:\/\/www.divertimundo.es\/elrinconcito\/?p=16764"},"modified":"2025-12-13T00:04:25","modified_gmt":"2025-12-12T23:04:25","slug":"mermelada-casera-con-melocoton-o-la-fruta-que-tu-elijas","status":"publish","type":"post","link":"http:\/\/www.divertimundo.es\/elrinconcito\/mermelada-casera-con-melocoton-o-la-fruta-que-tu-elijas\/","title":{"rendered":"Mermelada casera con melocot\u00f3n o la fruta que tu elijas"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_112023-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" src=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_112023-1024x768.jpg\" alt=\"\" class=\"wp-image-16766\" srcset=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_112023-1024x768.jpg 1024w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_112023-300x225.jpg 300w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_112023-768x576.jpg 768w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_112023-1536x1152.jpg 1536w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_112023-2048x1536.jpg 2048w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_112023-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p><strong>Ingredientes para 250 g de mermelada +o-<\/strong><\/p>\n\n\n\n<ul>\n<li>1 lata de melocot\u00f3n <strong>light sin az\u00facar de 400 g neto<\/strong><\/li>\n\n\n\n<li>20 o 40 g de<strong> Eritritol<\/strong> o az\u00facar <strong>probar<\/strong><\/li>\n\n\n\n<li>8 g de gelificante para <strong>hacer mermelada de Dr.Oetker<\/strong><\/li>\n\n\n\n<li>1 bote o <strong>vaso de cristal con tapa<\/strong> <\/li>\n\n\n\n<li>1 cazo <strong>para calentar<\/strong><\/li>\n<\/ul>\n\n\n\n<p><strong>En el mismo cazo<\/strong>, echar las mitades de melocot\u00f3n escurridas, el Eritritol seg\u00fan la fruta puede necesitar m\u00e1s o menos cantidad probar. Triturar con el brazo de la Minipimer, y dejar a tu gusto.<\/p>\n\n\n\n<p><strong>Ponemos el cazo en el calor<\/strong>, le a\u00f1adimos medio sobre de gelificante, y mezclar todo muy bien, con una esp\u00e1tula de silicona,&nbsp;<strong>a fuego bajo,<\/strong>&nbsp;el tiempo que indica el paquete, sin dejar de mover.<\/p>\n\n\n\n<p><strong>Luego pasar<\/strong> a un vaso o bote de cristal con tapa, y guardar en el frigor\u00edfico.<\/p>\n\n\n\n<p><strong>Si lo haces con fresas<\/strong>, yo suelo hacerlo con la bolsa de 300 g congelada, <strong>puedes descongela<\/strong>r en el frigor\u00edfico el d\u00eda anterior, y luego todo igual. <strong>Tambi\u00e9n hacerlo con la fruta que te guste fresca<\/strong>, que este un poco pasadita, o tambi\u00e9n congeladas, como Mix Tropical, etc.<\/p>\n\n\n\n<p><strong>Esta vez la hice para acompa\u00f1a<\/strong>r Foie Gras de pato fresco, marcado un poco en la sarten.<\/p>\n\n\n\n<figure class=\"is-layout-flex wp-block-gallery-1 wp-block-gallery has-nested-images columns-default is-cropped\">\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_112023-1-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" data-id=\"16775\"  src=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_112023-1-1024x768.jpg\" alt=\"\" class=\"wp-image-16775\" srcset=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_112023-1-1024x768.jpg 1024w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_112023-1-300x225.jpg 300w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_112023-1-768x576.jpg 768w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_112023-1-1536x1152.jpg 1536w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_112023-1-2048x1536.jpg 2048w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_112023-1-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">presentaci\u00f3n<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_105933-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" data-id=\"16774\"  src=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_105933-1024x768.jpg\" alt=\"\" class=\"wp-image-16774\" srcset=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_105933-1024x768.jpg 1024w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_105933-300x225.jpg 300w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_105933-768x576.jpg 768w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_105933-1536x1152.jpg 1536w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_105933-2048x1536.jpg 2048w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_105933-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">ingredientes<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110302-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" data-id=\"16773\"  src=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110302-1024x768.jpg\" alt=\"\" class=\"wp-image-16773\" srcset=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110302-1024x768.jpg 1024w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110302-300x225.jpg 300w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110302-768x576.jpg 768w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110302-1536x1152.jpg 1536w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110302-2048x1536.jpg 2048w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110302-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">echar en el cazo<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110450-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" data-id=\"16772\"  src=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110450-1024x768.jpg\" alt=\"\" class=\"wp-image-16772\" srcset=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110450-1024x768.jpg 1024w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110450-300x225.jpg 300w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110450-768x576.jpg 768w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110450-1536x1152.jpg 1536w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110450-2048x1536.jpg 2048w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110450-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">triturar<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110657-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" data-id=\"16770\"  src=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110657-1024x768.jpg\" alt=\"\" class=\"wp-image-16770\" srcset=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110657-1024x768.jpg 1024w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110657-300x225.jpg 300w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110657-768x576.jpg 768w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110657-1536x1152.jpg 1536w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110657-2048x1536.jpg 2048w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_110657-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">calentar y a\u00f1adir Gelificante<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_111650-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" data-id=\"16771\"  src=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_111650-1024x768.jpg\" alt=\"\" class=\"wp-image-16771\" srcset=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_111650-1024x768.jpg 1024w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_111650-300x225.jpg 300w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_111650-768x576.jpg 768w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_111650-1536x1152.jpg 1536w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_111650-2048x1536.jpg 2048w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_111650-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">mezclar todo muy bien<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_111957-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" data-id=\"16769\"  src=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_111957-1024x768.jpg\" alt=\"\" class=\"wp-image-16769\" srcset=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_111957-1024x768.jpg 1024w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_111957-300x225.jpg 300w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_111957-768x576.jpg 768w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_111957-1536x1152.jpg 1536w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_111957-2048x1536.jpg 2048w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_111957-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">repartir en el vaso<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/mermelada-casera-1.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" data-id=\"16767\"  src=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/mermelada-casera-1-1024x768.jpg\" alt=\"\" class=\"wp-image-16767\" srcset=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/mermelada-casera-1-1024x768.jpg 1024w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/mermelada-casera-1-300x225.jpg 300w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/mermelada-casera-1-768x576.jpg 768w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/mermelada-casera-1-1536x1152.jpg 1536w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/mermelada-casera-1-2048x1536.jpg 2048w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/mermelada-casera-1-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">ingredientes con fresas<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/mermelada-casera-2.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" data-id=\"16768\"  src=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/mermelada-casera-2-1024x768.jpg\" alt=\"\" class=\"wp-image-16768\" srcset=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/mermelada-casera-2-1024x768.jpg 1024w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/mermelada-casera-2-300x225.jpg 300w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/mermelada-casera-2-768x576.jpg 768w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/mermelada-casera-2-1536x1152.jpg 1536w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/mermelada-casera-2-2048x1536.jpg 2048w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/mermelada-casera-2-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">triturar <\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_135757-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" data-id=\"16776\"  src=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_135757-1024x768.jpg\" alt=\"\" class=\"wp-image-16776\" srcset=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_135757-1024x768.jpg 1024w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_135757-300x225.jpg 300w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_135757-768x576.jpg 768w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_135757-1536x1152.jpg 1536w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_135757-2048x1536.jpg 2048w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_135757-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><strong>Esta vez la hice para acompa\u00f1a<\/strong><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_141214-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" data-id=\"16777\"  src=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_141214-1024x768.jpg\" alt=\"\" class=\"wp-image-16777\" srcset=\"http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_141214-1024x768.jpg 1024w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_141214-300x225.jpg 300w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_141214-768x576.jpg 768w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_141214-1536x1152.jpg 1536w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_141214-2048x1536.jpg 2048w, http:\/\/www.divertimundo.es\/elrinconcito\/wp-content\/uploads\/2025\/12\/IMG_20251019_141214-400x300.jpg 400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Marcar el Foie Gras antes<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p>&#x1f4dc;<strong>Tienes la receta tambi\u00e9n en mi YouTube<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Mermelada casera con melocot\u00f3n o la fruta que tu elijas, frescas o congeladas #canaldecocina\" width=\"584\" height=\"329\" src=\"https:\/\/www.youtube.com\/embed\/pZKAgk28px4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Antes compraba las mermeladas cero az\u00facar, ahora las hago yo casera, y de la futa que me guste, con un poco de Gelificante, pero hay quien la hace tan solo con fruta, y sin triturarla, eso ya es cuesti\u00f3n de gusto. <a href=\"http:\/\/www.divertimundo.es\/elrinconcito\/mermelada-casera-con-melocoton-o-la-fruta-que-tu-elijas\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":[],"categories":[207],"tags":[2375,4836,4189,4761,4757,3750,4696,4835,2390,4695,4834],"_links":{"self":[{"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/posts\/16764"}],"collection":[{"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/comments?post=16764"}],"version-history":[{"count":4,"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/posts\/16764\/revisions"}],"predecessor-version":[{"id":16780,"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/posts\/16764\/revisions\/16780"}],"wp:attachment":[{"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/media?parent=16764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/categories?post=16764"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/tags?post=16764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}