{"id":2655,"count":2,"description":"","link":"http:\/\/www.divertimundo.es\/elrinconcito\/tag\/sobre-de-sopa\/","name":"sobre de sopa","slug":"sobre-de-sopa","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/tags\/2655"}],"collection":[{"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/posts?tags=2655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}