{"id":3486,"count":1,"description":"","link":"http:\/\/www.divertimundo.es\/elrinconcito\/tag\/croquetas-de-pollo\/","name":"croquetas de pollo","slug":"croquetas-de-pollo","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/tags\/3486"}],"collection":[{"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.divertimundo.es\/elrinconcito\/wp-json\/wp\/v2\/posts?tags=3486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}